{"id":356122,"date":"2024-12-11T09:30:41","date_gmt":"2024-12-11T08:30:41","guid":{"rendered":"https:\/\/www.leopizzo.com\/?post_type=product&#038;p=356122"},"modified":"2025-10-08T17:12:00","modified_gmt":"2025-10-08T15:12:00","slug":"anello-polo-smeraldo-contorno-bianco","status":"publish","type":"product","link":"https:\/\/www.leopizzo.com\/en\/product\/anello-polo-smeraldo-contorno-bianco\/","title":{"rendered":"Anello Polo"},"content":{"rendered":"<p>La collezione trae ispirazione dalla bellezza celestiale del firmamento e dalla fermezza del Polo Nord. Questi elementi sempre presenti nella nostra vita forniscono un punto di riferimento stabile, una bussola che non ci fa mai perdere l&#8217;orientamento.<br \/>\nProprio come le stelle che brillano nel cielo notturno, i nostri gioielli catturano la magia del cosmo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":356123,"template":"","meta":{"_acf_changed":false},"product_cat":[140],"product_tag":[],"class_list":{"0":"post-356122","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"line-polo","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anello Polo - Leo Pizzo<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leopizzo.com\/en\/product\/anello-polo-smeraldo-contorno-bianco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anello Polo - Leo Pizzo\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leopizzo.com\/en\/product\/anello-polo-smeraldo-contorno-bianco\/\" \/>\n<meta property=\"og:site_name\" content=\"Leo Pizzo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LeoPizzoGioielli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T15:12:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/\",\"url\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/\",\"name\":\"Anello Polo - Leo Pizzo\",\"isPartOf\":{\"@id\":\"https:\/\/www.leopizzo.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg\",\"datePublished\":\"2024-12-11T08:30:41+00:00\",\"dateModified\":\"2025-10-08T15:12:00+00:00\",\"description\":\"Scopri l'anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#primaryimage\",\"url\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg\",\"contentUrl\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg\",\"width\":1800,\"height\":1800,\"caption\":\"Anello Polo in oro bianco 18 carati con diamante taglio smeraldo e contorno\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leopizzo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.leopizzo.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anello Polo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leopizzo.com\/#website\",\"url\":\"https:\/\/www.leopizzo.com\/\",\"name\":\"Leo Pizzo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.leopizzo.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leopizzo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.leopizzo.com\/#organization\",\"name\":\"Leo Pizzo\",\"url\":\"https:\/\/www.leopizzo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png\",\"contentUrl\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png\",\"width\":2869,\"height\":936,\"caption\":\"Leo Pizzo\"},\"image\":{\"@id\":\"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LeoPizzoGioielli\/\",\"https:\/\/www.instagram.com\/leopizzoofficial\/?hl=it\",\"https:\/\/www.pinterest.it\/leopizzoofficial\/\",\"https:\/\/www.youtube.com\/channel\/UCoVL7as9APO0BAbI85tMAmA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anello Polo - Leo Pizzo","description":"Scopri l'anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leopizzo.com\/en\/product\/anello-polo-smeraldo-contorno-bianco\/","og_locale":"en_US","og_type":"article","og_title":"Anello Polo - Leo Pizzo","og_description":"Scopri l'anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante","og_url":"https:\/\/www.leopizzo.com\/en\/product\/anello-polo-smeraldo-contorno-bianco\/","og_site_name":"Leo Pizzo","article_publisher":"https:\/\/www.facebook.com\/LeoPizzoGioielli\/","article_modified_time":"2025-10-08T15:12:00+00:00","og_image":[{"width":1800,"height":1800,"url":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/","url":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/","name":"Anello Polo - Leo Pizzo","isPartOf":{"@id":"https:\/\/www.leopizzo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#primaryimage"},"image":{"@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg","datePublished":"2024-12-11T08:30:41+00:00","dateModified":"2025-10-08T15:12:00+00:00","description":"Scopri l'anello Polo in oro bianco 18 carati con diamanti naturali taglio smeraldo e brillante","breadcrumb":{"@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#primaryimage","url":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg","contentUrl":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2024\/12\/29046-B.jpg","width":1800,"height":1800,"caption":"Anello Polo in oro bianco 18 carati con diamante taglio smeraldo e contorno"},{"@type":"BreadcrumbList","@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-polo-smeraldo-contorno-bianco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leopizzo.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.leopizzo.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Anello Polo"}]},{"@type":"WebSite","@id":"https:\/\/www.leopizzo.com\/#website","url":"https:\/\/www.leopizzo.com\/","name":"Leo Pizzo","description":"","publisher":{"@id":"https:\/\/www.leopizzo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leopizzo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.leopizzo.com\/#organization","name":"Leo Pizzo","url":"https:\/\/www.leopizzo.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png","contentUrl":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png","width":2869,"height":936,"caption":"Leo Pizzo"},"image":{"@id":"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LeoPizzoGioielli\/","https:\/\/www.instagram.com\/leopizzoofficial\/?hl=it","https:\/\/www.pinterest.it\/leopizzoofficial\/","https:\/\/www.youtube.com\/channel\/UCoVL7as9APO0BAbI85tMAmA"]}]}},"_links":{"self":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product\/356122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/media\/356123"}],"wp:attachment":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/media?parent=356122"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product_cat?post=356122"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product_tag?post=356122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}