{"id":353938,"date":"2023-06-09T09:22:43","date_gmt":"2023-06-09T07:22:43","guid":{"rendered":"https:\/\/www.leopizzo.com\/?post_type=product&#038;p=353938"},"modified":"2025-10-08T16:36:07","modified_gmt":"2025-10-08T14:36:07","slug":"anello-candy-flora-smeraldi","status":"publish","type":"product","link":"https:\/\/www.leopizzo.com\/en\/product\/anello-candy-flora-smeraldi\/","title":{"rendered":"Anello Candy Flora"},"content":{"rendered":"<p>Colori vibranti e freschezza irresistibile: la Collezione Candy Flora \u00e8 un concentrato di gioia ed energia positiva, capace di illuminare ogni momento e migliorare subito l\u2019umore.<br \/>\nVivi un\u2019emozione preziosa e scopri la bellezza dei gioielli colorati Made in Italy firmati Leo Pizzo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante<\/p>","protected":false},"featured_media":353940,"template":"","meta":{"_acf_changed":false},"product_cat":[140],"product_tag":[],"class_list":{"0":"post-353938","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"line-candy-flora","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anello Candy Flora - Leo Pizzo<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leopizzo.com\/en\/product\/anello-candy-flora-smeraldi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anello Candy Flora - Leo Pizzo\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leopizzo.com\/en\/product\/anello-candy-flora-smeraldi\/\" \/>\n<meta property=\"og:site_name\" content=\"Leo Pizzo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LeoPizzoGioielli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T14:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/\",\"url\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/\",\"name\":\"Anello Candy Flora - Leo Pizzo\",\"isPartOf\":{\"@id\":\"https:\/\/www.leopizzo.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg\",\"datePublished\":\"2023-06-09T07:22:43+00:00\",\"dateModified\":\"2025-10-08T14:36:07+00:00\",\"description\":\"Scopri l'anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#primaryimage\",\"url\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg\",\"contentUrl\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg\",\"width\":1800,\"height\":1800,\"caption\":\"Anello Candy Flora in oro rosa 18 carati con smeraldi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leopizzo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.leopizzo.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anello Candy Flora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leopizzo.com\/#website\",\"url\":\"https:\/\/www.leopizzo.com\/\",\"name\":\"Leo Pizzo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.leopizzo.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leopizzo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.leopizzo.com\/#organization\",\"name\":\"Leo Pizzo\",\"url\":\"https:\/\/www.leopizzo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png\",\"contentUrl\":\"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png\",\"width\":2869,\"height\":936,\"caption\":\"Leo Pizzo\"},\"image\":{\"@id\":\"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LeoPizzoGioielli\/\",\"https:\/\/www.instagram.com\/leopizzoofficial\/?hl=it\",\"https:\/\/www.pinterest.it\/leopizzoofficial\/\",\"https:\/\/www.youtube.com\/channel\/UCoVL7as9APO0BAbI85tMAmA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anello Candy Flora - Leo Pizzo","description":"Scopri l'anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leopizzo.com\/en\/product\/anello-candy-flora-smeraldi\/","og_locale":"en_US","og_type":"article","og_title":"Anello Candy Flora - Leo Pizzo","og_description":"Scopri l'anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante","og_url":"https:\/\/www.leopizzo.com\/en\/product\/anello-candy-flora-smeraldi\/","og_site_name":"Leo Pizzo","article_publisher":"https:\/\/www.facebook.com\/LeoPizzoGioielli\/","article_modified_time":"2025-10-08T14:36:07+00:00","og_image":[{"width":1800,"height":1800,"url":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/","url":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/","name":"Anello Candy Flora - Leo Pizzo","isPartOf":{"@id":"https:\/\/www.leopizzo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#primaryimage"},"image":{"@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg","datePublished":"2023-06-09T07:22:43+00:00","dateModified":"2025-10-08T14:36:07+00:00","description":"Scopri l'anello fiore in oro rosa 18 carati con smeraldi naturali taglio brillante e diamante naturale taglio brillante","breadcrumb":{"@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#primaryimage","url":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg","contentUrl":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2023\/06\/27751DS.jpg","width":1800,"height":1800,"caption":"Anello Candy Flora in oro rosa 18 carati con smeraldi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.leopizzo.com\/prodotto\/anello-candy-flora-smeraldi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leopizzo.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.leopizzo.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Anello Candy Flora"}]},{"@type":"WebSite","@id":"https:\/\/www.leopizzo.com\/#website","url":"https:\/\/www.leopizzo.com\/","name":"Leo Pizzo","description":"","publisher":{"@id":"https:\/\/www.leopizzo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leopizzo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.leopizzo.com\/#organization","name":"Leo Pizzo","url":"https:\/\/www.leopizzo.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png","contentUrl":"https:\/\/www.leopizzo.com\/wp-content\/uploads\/2022\/12\/LeoPizzo-logo-1.png","width":2869,"height":936,"caption":"Leo Pizzo"},"image":{"@id":"https:\/\/www.leopizzo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LeoPizzoGioielli\/","https:\/\/www.instagram.com\/leopizzoofficial\/?hl=it","https:\/\/www.pinterest.it\/leopizzoofficial\/","https:\/\/www.youtube.com\/channel\/UCoVL7as9APO0BAbI85tMAmA"]}]}},"_links":{"self":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product\/353938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/media\/353940"}],"wp:attachment":[{"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/media?parent=353938"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product_cat?post=353938"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.leopizzo.com\/en\/wp-json\/wp\/v2\/product_tag?post=353938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}